{"id":1605,"date":"2021-10-24T22:45:00","date_gmt":"2021-10-25T05:45:00","guid":{"rendered":"https:\/\/yourwhiteknight.com\/reno\/?page_id=1605"},"modified":"2025-08-14T11:50:09","modified_gmt":"2025-08-14T18:50:09","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/yourwhiteknight.com\/reno\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"465\" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/1.-NEW-Logo-w-Premier-2025-Final-JPG-1024x465.jpg\" alt=\"\" class=\"wp-image-24433\" style=\"width:522px;height:auto\" srcset=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/1.-NEW-Logo-w-Premier-2025-Final-JPG-1024x465.jpg 1024w, https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/1.-NEW-Logo-w-Premier-2025-Final-JPG-300x136.jpg 300w, https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/1.-NEW-Logo-w-Premier-2025-Final-JPG-768x349.jpg 768w, https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/1.-NEW-Logo-w-Premier-2025-Final-JPG-1536x698.jpg 1536w, https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/1.-NEW-Logo-w-Premier-2025-Final-JPG-2048x931.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-paragraph\">\n<p class=\"has-text-align-left has-black-color has-text-color has-link-color has-large-font-size wp-elements-8ee85ae109dd663f9d586147ebe9d1ad wp-block-paragraph\"><strong><strong>Office Hours:<\/strong> <\/strong>Monday\u2013Friday, 9 AM\u20135 PM <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph\">\n<p class=\"has-text-align-left has-black-color has-text-color has-link-color has-large-font-size wp-elements-ec38885e9555cbfccf86a13044c07d3e wp-block-paragraph\"><strong><strong>Closed on bank holidays.<\/strong><br><strong>Parts Store:<\/strong> <\/strong>Daily; Saturday &amp; Sunday, 8 AM\u201312 PM <\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph\">\n<p class=\"has-text-align-left has-black-color has-text-color has-link-color has-large-font-size wp-elements-21c4d16ed756ca5c8bee651a375c2ab7 wp-block-paragraph\"><strong><strong>Closed on bank holidays.<\/strong><\/strong><\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph\">\n<p class=\"has-text-align-left has-black-color has-text-color has-link-color has-large-font-size wp-elements-4c19936d12246ed3adfe10979e5caf89 wp-block-paragraph\"><strong><br><strong>Sales Team:<\/strong> <\/strong>Available 7 days a week \u2014 call 775-322-8585 for assistance.<\/p>\n<\/div>\n\n<div class=\"wp-block-paragraph\">\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>**Office Hours may change at any time without notice**<\/strong><\/p>\n<\/div>\n\n\n            <section class=\"block-featured-team js-featured-team\">\n        <div class=\"block-featured-team__items\">\n            <div class=\"block-featured-team__content\">\n                <h2 class=\"block-featured-team__title\">Meet Our Knights<\/h2>\n                                    <p class=\"block-featured-team__text\">Service with a personal touch, we work as a team and our team will work for you!<\/p>\n                            <\/div>\n            <div class=\"block-featured-team__featured-items\">\n                <div class=\"block-featured-team__slider swiper-container\">\n                    <div class=\"block-featured-team__wrapper swiper-wrapper\">\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/white-knight-team\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2026\/03\/shield-2019png.png\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">White Knight Team<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/white-knight\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2022\/01\/shield-2019-namebadge.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">White Knight<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/wayne-carter\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/10\/Wayne-e1635193206673.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Wayne Carter<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/todd-andersen\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/10\/Todd-e1635372550352.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Todd Andersen<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/tiffany-anderson\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image --has-related-agent\" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/11\/Tiffany-Pic.jpg\"\/>\n                                                                                    <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/easton-anderson\/\"><img decoding=\"async\" class=\"block-featured-team__slide__image --related-agent\" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/Untitled-design-4.jpg\"\/><\/a>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Tiffany Anderson<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/tami-isom\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/yourwhiteknight.com\/reno\/wp-content\/themes\/white-knight\/assets\/placeholders\/agent-headshot.png\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Tami Isom<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/steven-mcallister\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/Untitled-design-e1754420687654.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Steven McAllister<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/roxanne\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/10\/Roo-e1635459154733.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Roxanne<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/rich-barbara\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/10\/RichBarb-e1635197103808.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Rich &#038; Barbara<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/renee-stewart\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2026\/03\/Untitled-2-x-2-in.png\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Renee  Stewart<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/ozzie-herrera\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2022\/03\/thumbnail_Attachment-1.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Ozzie Herrera<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/jennifer-harrison\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image --has-related-agent\" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2022\/12\/Jennifer-e1671128286709.jpg\"\/>\n                                                                                    <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/roxanne\/\"><img decoding=\"async\" class=\"block-featured-team__slide__image --related-agent\" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/10\/Roo-e1635459154733.jpg\"\/><\/a>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Jennifer Harrison<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/gustavo-barajas\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2023\/08\/Gustavo-Photo-3.jpeg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Gustavo Barajas<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/gadjo\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/11\/Godjo-2.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Gadjo<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/gabby-quigley\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/Photoroom_20250827_161542-e1756337999113.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Gabby Quigley<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/team-members\/easton-anderson\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/08\/Untitled-design-4.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Easton Anderson<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/cortney-wise\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/02\/Cortney.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Cortney Wise<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/cindy-miller\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2022\/03\/Cindy-5-e1698345840435.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Cindy Miller<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/bonnie-griggs\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2025\/09\/Untitled-design-3.png\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Bonnie  Griggs<\/p>\n                                <\/a>\n                            <\/div>\n                                                    <div class=\"block-featured-team__slide swiper-slide\">\n                                <a href=\"https:\/\/yourwhiteknight.com\/reno\/agents\/apolonia-sorianojuarez\/\" class=\"block-featured-team__container-link\">\n                                    <div class=\"block-featured-team__slide__image-container\">\n                                        <img decoding=\"async\" class=\"block-featured-team__slide__image \" src=\"https:\/\/storage.googleapis.com\/yourwhiteknight.com\/sites\/3\/2021\/10\/Apple-e1635353723425.jpg\"\/>\n                                                                            <\/div>\n                                    <p class=\"block-featured-team__slide__name\">Apolonia Soriano-Juarez<\/p>\n                                <\/a>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n                <div class=\"block-featured-team__slide-button-container\">\n                    <div class=\"block-featured-team__slide-button --prev js-button-prev\"><\/div>\n                    <div class=\"block-featured-team__slide-button --next js-button-next\"><\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"<p>Office Hours: Monday\u2013Friday, 9 AM\u20135 PM Closed on bank holidays.Parts Store: Daily; Saturday &amp; Sunday, 8 AM\u201312 PM Closed on bank holidays. Sales Team: Available 7 days a week \u2014&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-contact.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1605","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/pages\/1605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/comments?post=1605"}],"version-history":[{"count":0,"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/pages\/1605\/revisions"}],"wp:attachment":[{"href":"https:\/\/yourwhiteknight.com\/reno\/wp-json\/wp\/v2\/media?parent=1605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}